{"id":7573,"date":"2019-03-21T15:36:46","date_gmt":"2019-03-21T14:36:46","guid":{"rendered":"http:\/\/observatori.barcelonaturisme.com\/avis-legal\/"},"modified":"2025-03-18T16:03:28","modified_gmt":"2025-03-18T15:03:28","slug":"avis-legal","status":"publish","type":"page","link":"https:\/\/observatoriturisme.barcelona\/es\/avis-legal\/","title":{"rendered":"Aviso Legal"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"7573\" class=\"elementor elementor-7573 elementor-83\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4238f858 e-flex e-con-boxed e-con e-parent\" data-id=\"4238f858\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-59d5e9d e-con-full e-flex e-con e-child\" data-id=\"59d5e9d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5835bff elementor-widget elementor-widget-heading\" data-id=\"5835bff\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Aviso Legal<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1048af44 elementor-widget elementor-widget-text-editor\" data-id=\"1048af44\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3>El Ayuntamiento de Barcelona, a trav\u00e9s de sus webs:<\/h3><ul><li><i class=\"bcn-icon bcn-icon-info-actualitzada\"><\/i><p><strong>Busca proporcionar una informaci\u00f3n actualizada y de calidad sobre los servicios de la ciudad.<\/strong><\/p><p>La informaci\u00f3n que se difunde por medio de este web es la vigente en el momento de su publicaci\u00f3n y se actualizar\u00e1 con la m\u00e1xima celeridad posible.<\/p><p>En caso de que se publique en el web informaci\u00f3n facilitada por terceros, esta ser\u00e1 responsabilidad de la persona o entidad proveedora. El Ayuntamiento de Barcelona vela por que los proveedores de esta informaci\u00f3n garanticen su actualizaci\u00f3n y el respeto seg\u00fan la normativa vigente.<\/p><p>Es objetivo del Ayuntamiento que la informaci\u00f3n que se difunde sea completa, veraz, precisa, \u00fatil y accesible, y que cumpla los requisitos de calidad previstos por la legislaci\u00f3n vigente.<\/p><\/li><li><i class=\"bcn-icon bcn-icon-acces-obert\"><\/i><p><strong>Permite el acceso con independencia de la opci\u00f3n tecnol\u00f3gica elegida por los usuarios, particularmente mediante las tecnolog\u00edas basadas en est\u00e1ndares abiertos.<\/strong><\/p><\/li><li><i class=\"bcn-icon bcn-icon-proteccio-dades\"><\/i><p><strong>Garantiza la seguridad y la protecci\u00f3n de los datos personales.<\/strong><\/p><p>Para poder acceder a alguno de los servicios del web que dispongan de gesti\u00f3n o tr\u00e1mite espec\u00edfico, los usuarios y las usuarias deber\u00e1n aportar los datos personales imprescindibles para la prestaci\u00f3n del servicio solicitado.<\/p><p>Estos datos de car\u00e1cter personal se integran en las correspondientes actividades de tratamiento del Ayuntamiento de Barcelona y ser\u00e1n tratados con el fin espec\u00edfico de cada tratamiento de conformidad con la regulaci\u00f3n establecida por el Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo sobre protecci\u00f3n de datos de car\u00e1cter personal y las medidas de seguridad requeridas por la normativa legal, especialmente por el Esquema Nacional de Seguridad, teniendo en cuenta la tipolog\u00eda de los datos y los riesgos previsibles. El\u00a0<a title=\"Abrir en una nueva ventana\" href=\"https:\/\/ajuntament.barcelona.cat\/seuelectronica\/estatics\/files\/tractaments\/relacio_tractaments.pdf\" target=\"_blank\" rel=\"noopener\">registro de actividades<\/a>\u00a0de tratamiento se encuentra en el apartado \u201c<a title=\"Abrir en una nueva ventana\" href=\"https:\/\/seuelectronica.ajuntament.barcelona.cat\/es\/proteccion-de-datos\" target=\"_blank\" rel=\"noopener\">Protecci\u00f3n de datos<\/a>\u201d de la Sede electr\u00f3nica.<\/p><p>La legitimaci\u00f3n del tratamiento est\u00e1 basada de forma mayoritaria en el cumplimiento de una obligaci\u00f3n legal, aunque tambi\u00e9n puede estarlo en el consentimiento de la persona interesada y\/o en la protecci\u00f3n de los intereses vitales o la ejecuci\u00f3n de un contrato.<\/p><p>El plazo de conservaci\u00f3n de los datos depender\u00e1 de lo especificado para cada tratamiento de datos personales por parte de la legislaci\u00f3n espec\u00edfica y de los criterios de minimizaci\u00f3n que se deriven.<\/p><p>Los datos recogidos \u00fanicamente ser\u00e1n objeto de cesi\u00f3n previo consentimiento de la persona interesada o de acuerdo con lo previsto en la legislaci\u00f3n vigente.<\/p><p>El Ayuntamiento de Barcelona garantiza la confidencialidad en el tratamiento de los datos de car\u00e1cter personal, as\u00ed como la implantaci\u00f3n de las medidas, de orden t\u00e9cnico y organizativo, que garanticen la seguridad de acuerdo con el Reglamento (UE) 2016\/679 del Parlamento Europeo y la legislaci\u00f3n vigente en materia de protecci\u00f3n de datos.<\/p><p>Los ciudadanos interesados (usuarios) podr\u00e1n ejercer en todo momento los derechos que garantizan el control de sus datos personales: derechos de acceso, rectificaci\u00f3n, supresi\u00f3n, oposici\u00f3n y limitaci\u00f3n del tratamiento, previstos en la normativa vigente, enviando la solicitud v\u00eda virtual, postal o presencial, seg\u00fan lo que se dispone en la\u00a0<a title=\"Abrir en una nueva ventana\" href=\"https:\/\/seuelectronica.ajuntament.barcelona.cat\/es\/proteccion-de-datos\" target=\"_blank\" rel=\"noopener\">Sede electr\u00f3nica<\/a>.<\/p><p>El Ayuntamiento de Barcelona le informar\u00e1 sobre las actuaciones derivadas de su petici\u00f3n en el plazo de un mes. Si se trata de peticiones especialmente complejas, el plazo se puede ampliar dos meses m\u00e1s, hasta un m\u00e1ximo de tres meses, previa notificaci\u00f3n a la persona interesada de las causas que lo justifican.<\/p><p>El responsable de los tratamientos efectuados es la Alcald\u00eda del Ayuntamiento de Barcelona, con sede en la pl. Sant Jaume, 1, 08002, Barcelona.<\/p><p>El delegado de protecci\u00f3n de datos es la persona encargada de velar por que el Ayuntamiento de Barcelona cumpla correctamente la normativa de protecci\u00f3n de datos. Puede contactar dirigiendo un mensaje electr\u00f3nico mediante el siguiente\u00a0<a title=\"Abrir en una nueva ventana\" href=\"https:\/\/w10.bcn.cat\/StpQueixesWEB\/serveisIris.do?cbDetall=4845&amp;consulta=1&amp;directo=1&amp;i=e&amp;origen=DELEGAT_PROTECCIO_TUTELA_DRETS\" target=\"_blank\" rel=\"noopener\">formulario<\/a>, o bien enviando un escrito a la avenida Diagonal, 220, planta 4, 08018 Barcelona.<\/p><\/li><li><i class=\"bcn-icon bcn-icon-galetes\"><\/i><p><strong>Sigue una\u00a0<a title=\"Abrir en una nueva ventana\" href=\"https:\/\/www.barcelona.cat\/common\/cookies\/es\/cookies.html\" target=\"_blank\" rel=\"noopener\">pol\u00edtica de\u00a0<em>cookies<\/em><\/a>\u00a0respetuosa con la privacidad.<\/strong><\/p><p>Este sitio web utiliza cookies propias y de terceros para mejorar la experiencia de navegaci\u00f3n y ofrecer contenidos y servicios de inter\u00e9s.<\/p><\/li><li><i class=\"bcn-icon bcn-icon-difondre\"><\/i><p><strong>Permite y fomenta la reutilizaci\u00f3n de la informaci\u00f3n difundida, con los l\u00edmites que este aviso legal prev\u00e9 y que la legislaci\u00f3n vigente impone.<\/strong><\/p><p>El Ayuntamiento de Barcelona permite reutilizar todos los datos e informaciones difundidos por medio de este web, siempre que no se indique lo contrario, con las condiciones siguientes:<\/p><ul class=\"llistat-difondre\"><li><i class=\"bcn-icon-ok-bold\"><\/i><p>No alterar el contenido de la informaci\u00f3n.<\/p><\/li><li><i class=\"bcn-icon-ok-bold\"><\/i><p>No desnaturalizar el sentido de la informaci\u00f3n.<\/p><\/li><li><i class=\"bcn-icon-ok-bold\"><\/i><p>Mencionar la fuente de la informaci\u00f3n.<\/p><\/li><li><i class=\"bcn-icon-ok-bold\"><\/i><p>No dar a entender que el Ayuntamiento patrocina o apoya la actividad en la que se reutiliza la informaci\u00f3n.<\/p><\/li><\/ul><p>En todos los casos, la posibilidad de reutilizar informaci\u00f3n queda limitada por la necesaria protecci\u00f3n de otros derechos, bienes o intereses de acuerdo con lo establecido en la legislaci\u00f3n vigente. En particular, cualquier acto de reutilizaci\u00f3n de la informaci\u00f3n contenida en este web debe garantizar la protecci\u00f3n del r\u00e9gimen de propiedad intelectual e industrial y del r\u00e9gimen de protecci\u00f3n de los datos personales.<\/p><p>En concreto, la reutilizaci\u00f3n de obras y prestaciones protegidas por el r\u00e9gimen de propiedad intelectual queda sujeta a los t\u00e9rminos de la licencia de propiedad intelectual que se haya establecido en cada. Queda prohibida la reutilizaci\u00f3n de obras y prestaciones de las que se haya indicado la reserva de los derechos de propiedad intelectual.<\/p><\/li><li><i class=\"bcn-icon bcn-icon-copyright\"><\/i><p><strong>Protege la propiedad intelectual industrial y fomenta las licencias abiertas.<\/strong><\/p><p>El Ayuntamiento de Barcelona es el titular de los derechos de propiedad intelectual de las obras y prestaciones que integran este web, o bien posee la autorizaci\u00f3n de su uso. Esto incluye el dise\u00f1o gr\u00e1fico y el software de este web, como tambi\u00e9n los textos, las im\u00e1genes y las grabaciones que contiene. La reproducci\u00f3n, distribuci\u00f3n, comunicaci\u00f3n p\u00fablica o transformaci\u00f3n de estas obras y prestaciones requiere la autorizaci\u00f3n del titular, al margen de las actividades directamente autorizadas por la ley de propiedad intelectual.<\/p><p>En caso de que se muestren contenidos sometidos a una licencia Creative Commons, estos se especifican en el apartado \u201cCondiciones espec\u00edficas de este web\u201d.<\/p><p>Las marcas, nombres comerciales y signos distintivos que aparecen en los webs del Ayuntamiento pueden estar protegidos por reg\u00edmenes de propiedad industrial y pertenecen a sus titulares respectivos. Queda prohibido cualquier uso que no tenga la autorizaci\u00f3n del titular o que no est\u00e9 amparado por la ley.<\/p><p>Si cualquier ciudadano considera que este web o su contenido suponen la infracci\u00f3n de alg\u00fan derecho de propiedad intelectual o industrial, debe notificarlo al Ayuntamiento, indicando su nombre, la titularidad de derechos (aportando la prueba o acreditaci\u00f3n correspondiente) y el objeto del derecho supuestamente infringido.<\/p><\/li><li><i class=\"bcn-icon bcn-icon-xarxes-socials\"><\/i><p><strong>Est\u00e1 presente en diferentes redes sociales y plataformas.<\/strong><\/p><p>El Ayuntamiento est\u00e1 presente en diferentes redes sociales y plataformas, como Facebook, Twitter, Instagram, YouTube, Telegram, LinkedIn o Issuu. Cuando se accede a cualquiera de estas u otras redes, hay que tener en cuenta que las condiciones de uso aplicables son las que cada plataforma tiene establecidas, las cuales no est\u00e1n determinadas por el Ayuntamiento.<\/p><p>En caso de que se muestren v\u00eddeos de YouTube se estar\u00e1 utilizando la API de servicios de YouTube, en la que se aplican:<\/p><p>\u00a0<\/p><ul class=\"llistat-difondre\"><li><i class=\"bcn-icon-ok-bold\"><\/i><p>Las\u00a0<a title=\"Abrir en una nueva ventana\" href=\"https:\/\/www.youtube.com\/t\/terms\" target=\"_blank\" rel=\"noopener\">Condiciones Generales de YouTube<\/a><\/p><\/li><li><i class=\"bcn-icon-ok-bold\"><\/i><p>La\u00a0<a title=\"Abrir en una nueva ventana\" href=\"https:\/\/policies.google.com\/privacy?hl=es\" target=\"_blank\" rel=\"noopener\">Pol\u00edtica de Privacidad de Google<\/a>.<\/p><\/li><\/ul><p>\u00a0<\/p><\/li><li><i class=\"bcn-icon bcn-icon-marc-legal\"><\/i><p><strong>Se ajusta al marco legal en vigor en materia de responsabilidad por los contenidos.<\/strong><\/p><p>El Ayuntamiento asume, de acuerdo con la legislaci\u00f3n vigente, la responsabilidad por los contenidos de este web que hayan sido elaborados por el mismo Ayuntamiento. Con respecto a los contenidos suministrados por usuarios y terceros, les son de aplicaci\u00f3n las exclusiones de responsabilidad previstas en los art\u00edculos 13 a 17 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico. En particular, con respecto a los contenidos enlazados, se aplica la exclusi\u00f3n de responsabilidad del art\u00edculo 17 de la mencionada ley.<\/p><p>El Ayuntamiento no responde del mal uso que los usuarios puedan hacer de los contenidos del web. Tampoco se hace responsable de las dificultades de acceso que pueda haber para entrar al portal ni del mal funcionamiento de este que sea atribuible a causas ajenas al Ayuntamiento.<\/p><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Aviso Legal El Ayuntamiento de Barcelona, a trav\u00e9s de sus webs: Busca proporcionar una informaci\u00f3n actualizada y de calidad sobre los servicios de la ciudad. La informaci\u00f3n que se difunde por medio de este web es la vigente en el momento de su publicaci\u00f3n y se actualizar\u00e1 con la m\u00e1xima celeridad posible. En caso de [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-7573","page","type-page","status-publish","hentry"],"acf":[],"rankMath":{"parentDomain":"observatoriturisme.barcelona","noFollowDomains":[],"noFollowExcludeDomains":[],"noFollowExternalLinks":false,"featuredImageNotice":"La imagen destacada debe tener al menos 200 por 200 p\u00edxeles para que Facebook y otros sitios de redes sociales puedan escogerla.","pluginReviewed":false,"postSettings":{"linkSuggestions":true,"useFocusKeyword":false},"frontEndScore":false,"postName":"avis-legal","permalinkFormat":"https:\/\/observatoriturisme.barcelona\/es\/%pagename%\/","showLockModifiedDate":true,"assessor":{"focusKeywordLink":"https:\/\/observatoriturisme.barcelona\/wp-admin\/edit.php?focus_keyword=%focus_keyword%&post_type=%post_type%","hasTOCPlugin":true,"primaryTaxonomy":false,"serpData":{"title":"","description":"","focusKeywords":"","pillarContent":false,"canonicalUrl":"","breadcrumbTitle":"","advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":"","facebookHasOverlay":false,"facebookImageOverlay":"","facebookAuthor":"","twitterCardType":"","twitterUseFacebook":true,"twitterTitle":"","twitterDescription":"","twitterImage":"","twitterImageID":"","twitterHasOverlay":false,"twitterImageOverlay":"","twitterPlayerUrl":"","twitterPlayerSize":"","twitterPlayerStream":"","twitterPlayerStreamCtype":"","twitterAppDescription":"","twitterAppIphoneName":"","twitterAppIphoneID":"","twitterAppIphoneUrl":"","twitterAppIpadName":"","twitterAppIpadID":"","twitterAppIpadUrl":"","twitterAppGoogleplayName":"","twitterAppGoogleplayID":"","twitterAppGoogleplayUrl":"","twitterAppCountry":"","robots":{"index":true},"twitterAuthor":"nombre de usuario","primaryTerm":0,"authorName":"programacion","titleTemplate":"%title% %sep% %sitename%","descriptionTemplate":"%excerpt%","showScoreFrontend":true,"lockModifiedDate":false},"powerWords":["incre\u00edble","asombroso","maravilloso","\u00fanico","hermoso","felicidad","brillante","cautivador","carism\u00e1tico","impactante","claro","completamente","confidencial","confianza","significativo","creativo","definitivamente","delicioso","demostrar","apres\u00farate","decidido","digno","din\u00e1mico","impresionante","esencial","inspirador","innovador","intenso","eficaz","m\u00e1gico","magn\u00edfico","hist\u00f3rico","importante","incre\u00edble","indispensable","inolvidable","irresistible","legendario","luminoso","lujo","m\u00e1gico","magn\u00edfico","majestuoso","memorable","maravilloso","milagroso","motivador","necesario","nuevo","oficial","perfecto","apasionado","persuasivo","fenomenal","placer","popular","poder","prestigioso","prodigioso","profundo","pr\u00f3spero","poderoso","calidad","radiante","r\u00e1pido","exitoso","revolucionario","satisfecho","seguridad","sensacional","sereno","suntuoso","espl\u00e9ndido","sublime","sorprendente","talentoso","terror\u00edfico","\u00fanico","valor","vibrante","victorioso","vivo","verdaderamente","celoso","aut\u00e9ntico","aventurero","espectacular","exclusivo","garantizado","extraordinario","fabuloso","fascinante","formidable","genial","grandioso","gratuito","h\u00e1bil","ilimitado","impecable","infalible","infinitamente","influyente","ingenioso","inolvidable","irremplazable","l\u00edder","maestro","notable","novedoso","pionero","poderoso","reconocido","revolucionario","sorprendente","superior","triunfante","ultra","valiente","valioso","vanguardista","vigoroso","visionario","voluntad","vital","triunfo","glorioso","imparable","inigualable","inteligente","invencible","libertad","orgullo","paz","progreso","renovado","sabidur\u00eda","satisfacci\u00f3n","seguro","serenidad","superaci\u00f3n","talento","transcendente","transformador","valent\u00eda","victoria"],"diacritics":{"A":"[\\u0041\\u24B6\\uFF21\\u00C0\\u00C1\\u00C2\\u1EA6\\u1EA4\\u1EAA\\u1EA8\\u00C3\\u0100\\u0102\\u1EB0\\u1EAE\\u1EB4\\u1EB2\\u0226\\u01E0\\u00C4\\u01DE\\u1EA2\\u00C5\\u01FA\\u01CD\\u0200\\u0202\\u1EA0\\u1EAC\\u1EB6\\u1E00\\u0104\\u023A\\u2C6F]","AA":"[\\uA732]","AE":"[\\u00C6\\u01FC\\u01E2]","AO":"[\\uA734]","AU":"[\\uA736]","AV":"[\\uA738\\uA73A]","AY":"[\\uA73C]","B":"[\\u0042\\u24B7\\uFF22\\u1E02\\u1E04\\u1E06\\u0243\\u0182\\u0181]","C":"[\\u0043\\u24B8\\uFF23\\u0106\\u0108\\u010A\\u010C\\u00C7\\u1E08\\u0187\\u023B\\uA73E]","D":"[\\u0044\\u24B9\\uFF24\\u1E0A\\u010E\\u1E0C\\u1E10\\u1E12\\u1E0E\\u0110\\u018B\\u018A\\u0189\\uA779]","DZ":"[\\u01F1\\u01C4]","Dz":"[\\u01F2\\u01C5]","E":"[\\u0045\\u24BA\\uFF25\\u00C8\\u00C9\\u00CA\\u1EC0\\u1EBE\\u1EC4\\u1EC2\\u1EBC\\u0112\\u1E14\\u1E16\\u0114\\u0116\\u00CB\\u1EBA\\u011A\\u0204\\u0206\\u1EB8\\u1EC6\\u0228\\u1E1C\\u0118\\u1E18\\u1E1A\\u0190\\u018E]","F":"[\\u0046\\u24BB\\uFF26\\u1E1E\\u0191\\uA77B]","G":"[\\u0047\\u24BC\\uFF27\\u01F4\\u011C\\u1E20\\u011E\\u0120\\u01E6\\u0122\\u01E4\\u0193\\uA7A0\\uA77D\\uA77E]","H":"[\\u0048\\u24BD\\uFF28\\u0124\\u1E22\\u1E26\\u021E\\u1E24\\u1E28\\u1E2A\\u0126\\u2C67\\u2C75\\uA78D]","I":"[\\u0049\\u24BE\\uFF29\\u00CC\\u00CD\\u00CE\\u0128\\u012A\\u012C\\u0130\\u00CF\\u1E2E\\u1EC8\\u01CF\\u0208\\u020A\\u1ECA\\u012E\\u1E2C\\u0197]","J":"[\\u004A\\u24BF\\uFF2A\\u0134\\u0248]","K":"[\\u004B\\u24C0\\uFF2B\\u1E30\\u01E8\\u1E32\\u0136\\u1E34\\u0198\\u2C69\\uA740\\uA742\\uA744\\uA7A2]","L":"[\\u004C\\u24C1\\uFF2C\\u013F\\u0139\\u013D\\u1E36\\u1E38\\u013B\\u1E3C\\u1E3A\\u0141\\u023D\\u2C62\\u2C60\\uA748\\uA746\\uA780]","LJ":"[\\u01C7]","Lj":"[\\u01C8]","M":"[\\u004D\\u24C2\\uFF2D\\u1E3E\\u1E40\\u1E42\\u2C6E\\u019C]","N":"[\\u004E\\u24C3\\uFF2E\\u01F8\\u0143\\u00D1\\u1E44\\u0147\\u1E46\\u0145\\u1E4A\\u1E48\\u0220\\u019D\\uA790\\uA7A4]","NJ":"[\\u01CA]","Nj":"[\\u01CB]","O":"[\\u004F\\u24C4\\uFF2F\\u00D2\\u00D3\\u00D4\\u1ED2\\u1ED0\\u1ED6\\u1ED4\\u00D5\\u1E4C\\u022C\\u1E4E\\u014C\\u1E50\\u1E52\\u014E\\u022E\\u0230\\u00D6\\u022A\\u1ECE\\u0150\\u01D1\\u020C\\u020E\\u01A0\\u1EDC\\u1EDA\\u1EE0\\u1EDE\\u1EE2\\u1ECC\\u1ED8\\u01EA\\u01EC\\u00D8\\u01FE\\u0186\\u019F\\uA74A\\uA74C]","OI":"[\\u01A2]","OO":"[\\uA74E]","OU":"[\\u0222]","P":"[\\u0050\\u24C5\\uFF30\\u1E54\\u1E56\\u01A4\\u2C63\\uA750\\uA752\\uA754]","Q":"[\\u0051\\u24C6\\uFF31\\uA756\\uA758\\u024A]","R":"[\\u0052\\u24C7\\uFF32\\u0154\\u1E58\\u0158\\u0210\\u0212\\u1E5A\\u1E5C\\u0156\\u1E5E\\u024C\\u2C64\\uA75A\\uA7A6\\uA782]","S":"[\\u0053\\u24C8\\uFF33\\u1E9E\\u015A\\u1E64\\u015C\\u1E60\\u0160\\u1E66\\u1E62\\u1E68\\u0218\\u015E\\u2C7E\\uA7A8\\uA784]","T":"[\\u0054\\u24C9\\uFF34\\u1E6A\\u0164\\u1E6C\\u021A\\u0162\\u1E70\\u1E6E\\u0166\\u01AC\\u01AE\\u023E\\uA786]","TZ":"[\\uA728]","U":"[\\u0055\\u24CA\\uFF35\\u00D9\\u00DA\\u00DB\\u0168\\u1E78\\u016A\\u1E7A\\u016C\\u00DC\\u01DB\\u01D7\\u01D5\\u01D9\\u1EE6\\u016E\\u0170\\u01D3\\u0214\\u0216\\u01AF\\u1EEA\\u1EE8\\u1EEE\\u1EEC\\u1EF0\\u1EE4\\u1E72\\u0172\\u1E76\\u1E74\\u0244]","V":"[\\u0056\\u24CB\\uFF36\\u1E7C\\u1E7E\\u01B2\\uA75E\\u0245]","VY":"[\\uA760]","W":"[\\u0057\\u24CC\\uFF37\\u1E80\\u1E82\\u0174\\u1E86\\u1E84\\u1E88\\u2C72]","X":"[\\u0058\\u24CD\\uFF38\\u1E8A\\u1E8C]","Y":"[\\u0059\\u24CE\\uFF39\\u1EF2\\u00DD\\u0176\\u1EF8\\u0232\\u1E8E\\u0178\\u1EF6\\u1EF4\\u01B3\\u024E\\u1EFE]","Z":"[\\u005A\\u24CF\\uFF3A\\u0179\\u1E90\\u017B\\u017D\\u1E92\\u1E94\\u01B5\\u0224\\u2C7F\\u2C6B\\uA762]","a":"[\\u0061\\u24D0\\uFF41\\u1E9A\\u00E0\\u00E1\\u00E2\\u1EA7\\u1EA5\\u1EAB\\u1EA9\\u00E3\\u0101\\u0103\\u1EB1\\u1EAF\\u1EB5\\u1EB3\\u0227\\u01E1\\u00E4\\u01DF\\u1EA3\\u00E5\\u01FB\\u01CE\\u0201\\u0203\\u1EA1\\u1EAD\\u1EB7\\u1E01\\u0105\\u2C65\\u0250]","aa":"[\\uA733]","ae":"[\\u00E6\\u01FD\\u01E3]","ao":"[\\uA735]","au":"[\\uA737]","av":"[\\uA739\\uA73B]","ay":"[\\uA73D]","b":"[\\u0062\\u24D1\\uFF42\\u1E03\\u1E05\\u1E07\\u0180\\u0183\\u0253]","c":"[\\u0063\\u24D2\\uFF43\\u0107\\u0109\\u010B\\u010D\\u00E7\\u1E09\\u0188\\u023C\\uA73F\\u2184]","d":"[\\u0064\\u24D3\\uFF44\\u1E0B\\u010F\\u1E0D\\u1E11\\u1E13\\u1E0F\\u0111\\u018C\\u0256\\u0257\\uA77A]","dz":"[\\u01F3\\u01C6]","e":"[\\u0065\\u24D4\\uFF45\\u00E8\\u00E9\\u00EA\\u1EC1\\u1EBF\\u1EC5\\u1EC3\\u1EBD\\u0113\\u1E15\\u1E17\\u0115\\u0117\\u00EB\\u1EBB\\u011B\\u0205\\u0207\\u1EB9\\u1EC7\\u0229\\u1E1D\\u0119\\u1E19\\u1E1B\\u0247\\u025B\\u01DD]","f":"[\\u0066\\u24D5\\uFF46\\u1E1F\\u0192\\uA77C]","g":"[\\u0067\\u24D6\\uFF47\\u01F5\\u011D\\u1E21\\u011F\\u0121\\u01E7\\u0123\\u01E5\\u0260\\uA7A1\\u1D79\\uA77F]","h":"[\\u0068\\u24D7\\uFF48\\u0125\\u1E23\\u1E27\\u021F\\u1E25\\u1E29\\u1E2B\\u1E96\\u0127\\u2C68\\u2C76\\u0265]","hv":"[\\u0195]","i":"[\\u0069\\u24D8\\uFF49\\u00EC\\u00ED\\u00EE\\u0129\\u012B\\u012D\\u00EF\\u1E2F\\u1EC9\\u01D0\\u0209\\u020B\\u1ECB\\u012F\\u1E2D\\u0268\\u0131]","j":"[\\u006A\\u24D9\\uFF4A\\u0135\\u01F0\\u0249]","k":"[\\u006B\\u24DA\\uFF4B\\u1E31\\u01E9\\u1E33\\u0137\\u1E35\\u0199\\u2C6A\\uA741\\uA743\\uA745\\uA7A3]","l":"[\\u006C\\u24DB\\uFF4C\\u0140\\u013A\\u013E\\u1E37\\u1E39\\u013C\\u1E3D\\u1E3B\\u017F\\u0142\\u019A\\u026B\\u2C61\\uA749\\uA781\\uA747]","lj":"[\\u01C9]","m":"[\\u006D\\u24DC\\uFF4D\\u1E3F\\u1E41\\u1E43\\u0271\\u026F]","n":"[\\u006E\\u24DD\\uFF4E\\u01F9\\u0144\\u00F1\\u1E45\\u0148\\u1E47\\u0146\\u1E4B\\u1E49\\u019E\\u0272\\u0149\\uA791\\uA7A5]","nj":"[\\u01CC]","o":"[\\u006F\\u24DE\\uFF4F\\u00F2\\u00F3\\u00F4\\u1ED3\\u1ED1\\u1ED7\\u1ED5\\u00F5\\u1E4D\\u022D\\u1E4F\\u014D\\u1E51\\u1E53\\u014F\\u022F\\u0231\\u00F6\\u022B\\u1ECF\\u0151\\u01D2\\u020D\\u020F\\u01A1\\u1EDD\\u1EDB\\u1EE1\\u1EDF\\u1EE3\\u1ECD\\u1ED9\\u01EB\\u01ED\\u00F8\\u01FF\\u0254\\uA74B\\uA74D\\u0275]","oi":"[\\u01A3]","ou":"[\\u0223]","oo":"[\\uA74F]","p":"[\\u0070\\u24DF\\uFF50\\u1E55\\u1E57\\u01A5\\u1D7D\\uA751\\uA753\\uA755]","q":"[\\u0071\\u24E0\\uFF51\\u024B\\uA757\\uA759]","r":"[\\u0072\\u24E1\\uFF52\\u0155\\u1E59\\u0159\\u0211\\u0213\\u1E5B\\u1E5D\\u0157\\u1E5F\\u024D\\u027D\\uA75B\\uA7A7\\uA783]","s":"[\\u0073\\u24E2\\uFF53\\u015B\\u1E65\\u015D\\u1E61\\u0161\\u1E67\\u1E63\\u1E69\\u0219\\u015F\\u023F\\uA7A9\\uA785\\u1E9B]","ss":"[\\u00DF]","t":"[\\u0074\\u24E3\\uFF54\\u1E6B\\u1E97\\u0165\\u1E6D\\u021B\\u0163\\u1E71\\u1E6F\\u0167\\u01AD\\u0288\\u2C66\\uA787]","tz":"[\\uA729]","u":"[\\u0075\\u24E4\\uFF55\\u00F9\\u00FA\\u00FB\\u0169\\u1E79\\u016B\\u1E7B\\u016D\\u00FC\\u01DC\\u01D8\\u01D6\\u01DA\\u1EE7\\u016F\\u0171\\u01D4\\u0215\\u0217\\u01B0\\u1EEB\\u1EE9\\u1EEF\\u1EED\\u1EF1\\u1EE5\\u1E73\\u0173\\u1E77\\u1E75\\u0289]","v":"[\\u0076\\u24E5\\uFF56\\u1E7D\\u1E7F\\u028B\\uA75F\\u028C]","vy":"[\\uA761]","w":"[\\u0077\\u24E6\\uFF57\\u1E81\\u1E83\\u0175\\u1E87\\u1E85\\u1E98\\u1E89\\u2C73]","x":"[\\u0078\\u24E7\\uFF58\\u1E8B\\u1E8D]","y":"[\\u0079\\u24E8\\uFF59\\u1EF3\\u00FD\\u0177\\u1EF9\\u0233\\u1E8F\\u00FF\\u1EF7\\u1E99\\u1EF5\\u01B4\\u024F\\u1EFF]","z":"[\\u007A\\u24E9\\uFF5A\\u017A\\u1E91\\u017C\\u017E\\u1E93\\u1E95\\u01B6\\u0225\\u0240\\u2C6C\\uA763]"},"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasRedirection":false,"hasBreadcrumb":false},"homeUrl":"https:\/\/observatoriturisme.barcelona\/es\/","objectID":7573,"objectType":"post","locale":"es","localeFull":"es_ES","overlayImages":{"play":{"name":"Icono de reproducci\u00f3n","url":"https:\/\/observatoriturisme.barcelona\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","path":"\/var\/www\/html\/observatori\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-play.png","position":"middle_center"},"gif":{"name":"Icono GIF","url":"https:\/\/observatoriturisme.barcelona\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","path":"\/var\/www\/html\/observatori\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/icon-gif.png","position":"middle_center"}},"defautOgImage":"https:\/\/observatoriturisme.barcelona\/wp-content\/uploads\/2025\/01\/header_OTB_210319-01_nologos.jpg","customPermalinks":true,"isUserRegistered":false,"autoSuggestKeywords":false,"connectSiteUrl":"https:\/\/rankmath.com\/auth?site=https%3A%2F%2Fobservatoriturisme.barcelona%2Fes%2F&r=https%3A%2F%2Fobservatoriturisme.barcelona%2Fes%2Fwp-json%2Fwp%2Fv2%2Fpages%2F7573%3Fnonce%3Daeabce0211","maxTags":5,"trendsIcon":"<svg viewBox=\"0 0 610 610\"><path d=\"M18.85,446,174.32,290.48l58.08,58.08L76.93,504a14.54,14.54,0,0,1-20.55,0L18.83,466.48a14.54,14.54,0,0,1,0-20.55Z\" style=\"fill:#4285f4\"\/><path d=\"M242.65,242.66,377.59,377.6l-47.75,47.75a14.54,14.54,0,0,1-20.55,0L174.37,290.43l47.75-47.75A14.52,14.52,0,0,1,242.65,242.66Z\" style=\"fill:#ea4335\"\/><polygon points=\"319.53 319.53 479.26 159.8 537.34 217.88 377.61 377.62 319.53 319.53\" style=\"fill:#fabb05\"\/><path d=\"M594.26,262.73V118.61h0a16.94,16.94,0,0,0-16.94-16.94H433.2a16.94,16.94,0,0,0-12,28.92L565.34,274.71h0a16.94,16.94,0,0,0,28.92-12Z\" style=\"fill:#34a853\"\/><rect width=\"610\" height=\"610\" style=\"fill:none\"\/><\/svg>","showScore":true,"siteFavIcon":"https:\/\/observatoriturisme.barcelona\/wp-content\/uploads\/2024\/12\/cropped-OTB_icon-32x32.jpg","canUser":{"general":false,"advanced":false,"snippet":false,"social":false,"analysis":false,"analytics":false,"content_ai":false},"showKeywordIntent":true,"isPro":false,"is_front_page":false,"trendsUpgradeLink":"https:\/\/rankmath.com\/pricing\/?utm_source=Plugin&utm_medium=CE%20General%20Tab%20Trends&utm_campaign=WP","trendsUpgradeLabel":"Actualizar","trendsPreviewImage":"https:\/\/observatoriturisme.barcelona\/wp-content\/plugins\/seo-by-rank-math\/assets\/admin\/img\/trends-preview.jpg","currentEditor":false,"homepageData":{"assessor":{"powerWords":["incre\u00edble","asombroso","maravilloso","\u00fanico","hermoso","felicidad","brillante","cautivador","carism\u00e1tico","impactante","claro","completamente","confidencial","confianza","significativo","creativo","definitivamente","delicioso","demostrar","apres\u00farate","decidido","digno","din\u00e1mico","impresionante","esencial","inspirador","innovador","intenso","eficaz","m\u00e1gico","magn\u00edfico","hist\u00f3rico","importante","incre\u00edble","indispensable","inolvidable","irresistible","legendario","luminoso","lujo","m\u00e1gico","magn\u00edfico","majestuoso","memorable","maravilloso","milagroso","motivador","necesario","nuevo","oficial","perfecto","apasionado","persuasivo","fenomenal","placer","popular","poder","prestigioso","prodigioso","profundo","pr\u00f3spero","poderoso","calidad","radiante","r\u00e1pido","exitoso","revolucionario","satisfecho","seguridad","sensacional","sereno","suntuoso","espl\u00e9ndido","sublime","sorprendente","talentoso","terror\u00edfico","\u00fanico","valor","vibrante","victorioso","vivo","verdaderamente","celoso","aut\u00e9ntico","aventurero","espectacular","exclusivo","garantizado","extraordinario","fabuloso","fascinante","formidable","genial","grandioso","gratuito","h\u00e1bil","ilimitado","impecable","infalible","infinitamente","influyente","ingenioso","inolvidable","irremplazable","l\u00edder","maestro","notable","novedoso","pionero","poderoso","reconocido","revolucionario","sorprendente","superior","triunfante","ultra","valiente","valioso","vanguardista","vigoroso","visionario","voluntad","vital","triunfo","glorioso","imparable","inigualable","inteligente","invencible","libertad","orgullo","paz","progreso","renovado","sabidur\u00eda","satisfacci\u00f3n","seguro","serenidad","superaci\u00f3n","talento","transcendente","transformador","valent\u00eda","victoria"],"diacritics":true,"researchesTests":["contentHasTOC","contentHasShortParagraphs","contentHasAssets","keywordInTitle","keywordInMetaDescription","keywordInPermalink","keywordIn10Percent","keywordInContent","keywordInSubheadings","keywordInImageAlt","keywordDensity","keywordNotUsed","lengthContent","lengthPermalink","linksHasInternal","linksHasExternals","linksNotAllExternals","titleStartWithKeyword","titleSentiment","titleHasPowerWords","titleHasNumber","hasContentAI"],"hasBreadcrumb":false,"serpData":{"title":"%sitename% %page% %sep% %sitedesc%","description":"","titleTemplate":"%sitename% %page% %sep% %sitedesc%","descriptionTemplate":"","focusKeywords":"","breadcrumbTitle":"Home","robots":{"index":true},"advancedRobots":[],"facebookTitle":"","facebookDescription":"","facebookImage":"","facebookImageID":""}}},"tocTitle":"Table of Contents","tocExcludeHeadings":[],"listStyle":"ul"},"_links":{"self":[{"href":"https:\/\/observatoriturisme.barcelona\/es\/wp-json\/wp\/v2\/pages\/7573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/observatoriturisme.barcelona\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/observatoriturisme.barcelona\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/observatoriturisme.barcelona\/es\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/observatoriturisme.barcelona\/es\/wp-json\/wp\/v2\/comments?post=7573"}],"version-history":[{"count":4,"href":"https:\/\/observatoriturisme.barcelona\/es\/wp-json\/wp\/v2\/pages\/7573\/revisions"}],"predecessor-version":[{"id":7581,"href":"https:\/\/observatoriturisme.barcelona\/es\/wp-json\/wp\/v2\/pages\/7573\/revisions\/7581"}],"wp:attachment":[{"href":"https:\/\/observatoriturisme.barcelona\/es\/wp-json\/wp\/v2\/media?parent=7573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}